{"id":311,"date":"2023-12-13T19:28:43","date_gmt":"2023-12-13T18:28:43","guid":{"rendered":"https:\/\/cicloamatour.it\/strada\/?page_id=311"},"modified":"2023-12-13T19:28:43","modified_gmt":"2023-12-13T18:28:43","slug":"cookie-policy","status":"publish","type":"page","link":"https:\/\/cicloamatour.it\/strada\/cookie-policy\/","title":{"rendered":"Cookie Policy"},"content":{"rendered":"\n<p>I Cookie sono costituiti da porzioni di codice installate all\u2019interno del browser che assistono il Titolare nell\u2019erogazione del Servizio in base alle finalit\u00e0 descritte. Alcune delle finalit\u00e0 di installazione dei Cookie potrebbero, inoltre, necessitare del consenso dell\u2019Utente.<\/p>\n\n\n\n<p>Quando l\u2019installazione di Cookies avviene sulla base del consenso, tale consenso pu\u00f2 essere revocato liberamente in ogni momento seguendo le istruzioni contenute in questo documento.<\/p>\n\n\n\n<p><strong>Cookie tecnici e di statistica aggregata<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Attivit\u00e0 strettamente necessarie al funzionamento<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Questa Applicazione utilizza Cookie per salvare la sessione dell\u2019Utente e per svolgere altre attivit\u00e0 strettamente necessarie al funzionamento di questa Applicazione, ad esempio in relazione alla distribuzione del traffico.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Attivit\u00e0 di salvataggio delle preferenze, ottimizzazione e statistica<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Questa Applicazione utilizza Cookie per salvare le preferenze di navigazione ed ottimizzare l\u2019esperienza di navigazione dell\u2019Utente. Fra questi Cookie rientrano, ad esempio, quelli per impostare la lingua e la valuta o per la gestione di statistiche da parte del Titolare del sito.<\/p>\n\n\n\n<p><strong>Altre tipologie di Cookie o strumenti terzi che potrebbero installarne<\/strong><\/p>\n\n\n\n<p>Alcuni dei servizi elencati di seguito raccolgono statistiche in forma aggregata ed anonima e potrebbero non richiedere il consenso dell\u2019Utente o potrebbero essere gestiti direttamente dal Titolare \u2013 a seconda di quanto descritto \u2013 senza l\u2019ausilio di terzi.<\/p>\n\n\n\n<p>Qualora fra gli strumenti indicati in seguito fossero presenti servizi gestiti da terzi, questi potrebbero \u2013 in aggiunta a quanto specificato ed anche all\u2019insaputa del Titolare \u2013 compiere attivit\u00e0 di tracciamento dell\u2019Utente. Per informazioni dettagliate in merito, si consiglia di consultare le privacy policy dei servizi elencati.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Interazione con social network e piattaforme esterne<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Questo tipo di servizi permette di effettuare interazioni con i social network, o con altre piattaforme esterne, direttamente dalle pagine di questa Applicazione.<br>Le interazioni e le informazioni acquisite da questa Applicazione sono in ogni caso soggette alle impostazioni privacy dell\u2019Utente relative ad ogni social network.<br>Nel caso in cui sia installato un servizio di interazione con i social network, \u00e8 possibile che, anche nel caso gli Utenti non utilizzino il servizio, lo stesso raccolga dati di traffico relativi alle pagine in cui \u00e8 installato.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Protezione dallo SPAM<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Questo tipo di servizi analizza il traffico di questa Applicazione, potenzialmente contenente Dati Personali degli Utenti, al fine di filtrarlo da parti di traffico, messaggi e contenuti riconosciuti come SPAM.<\/p>\n\n\n\n<p><strong>Google reCAPTCHA (Google Inc.)<\/strong><\/p>\n\n\n\n<p>Google reCAPTCHA \u00e8 un servizio di protezione dallo SPAM fornito da Google Inc.<br>L\u2019utilizzo del sistema reCAPTCHA \u00e8 soggetto alla&nbsp;<a href=\"https:\/\/www.google.com\/intl\/it\/policies\/privacy\/\">privacy policy<\/a>&nbsp;e ai&nbsp;<a href=\"https:\/\/www.google.com\/intl\/it\/policies\/terms\/\">termini di utilizzo<\/a>&nbsp;di Google.<\/p>\n\n\n\n<p>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/p>\n\n\n\n<p>Luogo del trattamento: Stati Uniti \u2013&nbsp;<a href=\"https:\/\/www.google.com\/intl\/it\/policies\/privacy\/\">Privacy Policy<\/a>. Soggetto aderente al Privacy Shield.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Statistica<\/strong><\/li>\n<\/ul>\n\n\n\n<p>I servizi contenuti nella presente sezione permettono al Titolare del Trattamento di monitorare e analizzare i dati di traffico e servono a tener traccia del comportamento dell\u2019Utente.<\/p>\n\n\n\n<p><strong>Google Analytics (Google Inc.)<\/strong><\/p>\n\n\n\n<p>Google Analytics \u00e8 un servizio di analisi web fornito da Google Inc. (\u201cGoogle\u201d). Google utilizza i Dati Personali raccolti allo scopo di tracciare ed esaminare l\u2019utilizzo di questa Applicazione, compilare report e condividerli con gli altri servizi sviluppati da Google.<br>Google potrebbe utilizzare i Dati Personali per contestualizzare e personalizzare gli annunci del proprio network pubblicitario.<\/p>\n\n\n\n<p><strong>Dati Personali raccolti: Cookie e Dati di utilizzo.<\/strong><\/p>\n\n\n\n<p>Luogo del trattamento: Stati Uniti \u2013&nbsp;<a href=\"https:\/\/www.google.com\/intl\/it\/policies\/privacy\/\">Privacy Policy<\/a>&nbsp;\u2013&nbsp;<a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=it\">Opt Out<\/a>. Soggetto aderente al Privacy Shield.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Visualizzazione di contenuti da piattaforme esterne<\/li>\n<\/ul>\n\n\n\n<p>Questo tipo di servizi permette di visualizzare contenuti ospitati su piattaforme esterne direttamente dalle pagine di questa Applicazione e di interagire con essi.<br>Nel caso in cui sia installato un servizio di questo tipo, \u00e8 possibile che, anche nel caso gli Utenti non utilizzino il servizio, lo stesso raccolga dati di traffico relativi alle pagine in cui \u00e8 installato.<\/p>\n\n\n\n<p><strong>Come posso esprimere il consenso all\u2019installazione di Cookie?<\/strong><\/p>\n\n\n\n<p>In aggiunta a quanto indicato in questo documento, l\u2019Utente pu\u00f2 gestire le preferenze relative ai Cookie direttamente all\u2019interno del proprio browser ed impedire \u2013 ad esempio \u2013 che terze parti possano installarne. Tramite le preferenze del browser \u00e8 inoltre possibile eliminare i Cookie installati in passato, incluso il Cookie in cui venga eventualmente salvato il consenso all\u2019installazione di Cookie da parte di questo sito. L\u2019Utente pu\u00f2 trovare informazioni su come gestire i Cookie con alcuni dei browser pi\u00f9 diffusi ad esempio ai seguenti indirizzi:&nbsp;<a href=\"https:\/\/support.google.com\/chrome\/answer\/95647?hl=it&amp;p=cpn_cookies\">Google Chrome<\/a>,&nbsp;<a href=\"https:\/\/support.mozilla.org\/it\/kb\/Attivare%20e%20disattivare%20i%20cookie\">Mozilla Firefox<\/a>,&nbsp;<a href=\"https:\/\/support.apple.com\/kb\/PH21411\">Apple Safari<\/a>&nbsp;e&nbsp;<a href=\"http:\/\/windows.microsoft.com\/it-it\/windows-vista\/block-or-allow-cookies\">Microsoft Internet Explorer<\/a>.<\/p>\n\n\n\n<p>Con riferimento a Cookie installati da terze parti, l\u2019Utente pu\u00f2 inoltre gestire le proprie impostazioni e revocare il consenso visitando il relativo link di opt out (qualora disponibile), utilizzando gli strumenti descritti nella privacy policy della terza parte o contattando direttamente la stessa.<\/p>\n\n\n\n<p>Fermo restando quanto precede, l\u2019Utente pu\u00f2 avvalersi delle informazioni fornite da&nbsp;<a href=\"http:\/\/www.youronlinechoices.eu\/\">EDAA<\/a>&nbsp;(UE),&nbsp;<a href=\"https:\/\/www.networkadvertising.org\/understanding-digital-advertising\">Network Advertising Initiative<\/a>&nbsp;(USA) e&nbsp;<a href=\"https:\/\/www.aboutads.info\/consumers\/\">Digital Advertising Alliance<\/a>&nbsp;(USA),&nbsp;<a href=\"https:\/\/youradchoices.ca\/understanding-online-advertising\/\">DAAC<\/a>&nbsp;(Canada),&nbsp;<a href=\"http:\/\/www.ddai.info\/optout\">DDAI<\/a>&nbsp;(Giappone) o altri servizi analoghi. Con questi servizi \u00e8 possibile gestire le preferenze di tracciamento della maggior parte degli strumenti pubblicitari. Il Titolare, pertanto, consiglia agli Utenti di utilizzare tali risorse in aggiunta alle informazioni fornite dal presente documento.<\/p>\n\n\n\n<p><strong>Titolare del Trattamento dei Dati<\/strong><\/p>\n\n\n\n<p><strong>BIKEMANIA A.S.D.<\/strong>&nbsp;\u2013 VIALE GRAMSCI 174\/C \u2013 74023 \u2013 GROTTAGLIE \u2013 TA \u2013 Cod. FCI: 14L1760<\/p>\n\n\n\n<p><strong>A.S.D. MMTB MARTINA FRANCA<\/strong>&nbsp;\u2013 VIA MONSIGNOR O.RUGGIERI 34\/D \u2013 74015 \u2013 MARTINA FRANCA \u2013 TA \u2013 Cod. FCI: 14X1686<\/p>\n\n\n\n<p><strong>ASD SPES<\/strong>&nbsp;\u2013 VIA AMMIRAGLIO MILLO, NC \u2013 70011 \u2013 ALBEROBELLO \u2013 BA \u2013 Cod. FCI: 14D1645<\/p>\n\n\n\n<p><strong>ASD CHIALA\u2019 CYCLING TEAM LOCOROTONDO<\/strong>&nbsp;\u2013 VIA DEI TRULLARI, 12 \u2013 70010 \u2013 LOCOROTONDO \u2013 BA \u2013 Cod. FCI: 14R1700<\/p>\n\n\n\n<p><strong>ASD CICLISTICA COLLEPASSESE<\/strong>&nbsp;\u2013 VIA CARABINIERE ROLLO, 4 \u2013 73040 \u2013 COLLEPASSO \u2013 LE \u2013 Cod. FCI: 14A0152<\/p>\n\n\n\n<p><strong>GSC ARNESANO&nbsp;<\/strong>\u2013 VIA INDENNITATE, 20 \u2013 73010 \u2013 ARNESANO \u2013 LE \u2013 Cod. FCI 14V1844<\/p>\n\n\n\n<p><strong>CARBINIA BIKE CAROVIGNO<\/strong> \u2013 72012 \u2013 VIA DR.VITO O.CAVALLO, 52 \u2013 CAROVIGNO BR<\/p>\n\n\n\n<p><strong>Indirizzo email del Titolare:<\/strong>&nbsp;info@cicloamatour.it<\/p>\n\n\n\n<p>Dal momento che l\u2019installazione di Cookie e di altri sistemi di tracciamento operata da terze parti tramite i servizi utilizzati all\u2019interno di questa Applicazione non pu\u00f2 essere tecnicamente controllata dal Titolare, ogni riferimento specifico a Cookie e sistemi di tracciamento installati da terze parti \u00e8 da considerarsi indicativo. Per ottenere informazioni complete, l\u2019Utente \u00e8 invitato a consultare la privacy policy degli eventuali servizi terzi elencati in questo documento.<\/p>\n\n\n\n<p>Vista l\u2019oggettiva complessit\u00e0 di identificazione delle tecnologie basate sui Cookie l\u2019Utente \u00e8 invitato a contattare il Titolare qualora volesse ricevere qualunque approfondimento relativo all\u2019utilizzo dei Cookie stessi tramite questa Applicazione.<\/p>\n\n\n\n<p><strong>Definizioni e riferimenti legali<\/strong><\/p>\n\n\n\n<p><strong>Dati Personali (o Dati)<\/strong><\/p>\n\n\n\n<p>Costituisce dato personale qualunque informazione che, direttamente o indirettamente, anche in collegamento con qualsiasi altra informazione, ivi compreso un numero di identificazione personale, renda identificata o identificabile una persona fisica.<\/p>\n\n\n\n<p><strong>Dati di Utilizzo<\/strong><\/p>\n\n\n\n<p>Sono le informazioni raccolte automaticamente attraverso questa Applicazione (anche da applicazioni di parti terze integrate in questa Applicazione), tra cui: gli indirizzi IP o i nomi a dominio dei computer utilizzati dall\u2019Utente che si connette con questa Applicazione, gli indirizzi in notazione URI (Uniform Resource Identifier), l\u2019orario della richiesta, il metodo utilizzato nell\u2019inoltrare la richiesta al server, la dimensione del file ottenuto in risposta, il codice numerico indicante lo stato della risposta dal server (buon fine, errore, ecc.) il paese di provenienza, le caratteristiche del browser e del sistema operativo utilizzati dal visitatore, le varie connotazioni temporali della visita (ad esempio il tempo di permanenza su ciascuna pagina) e i dettagli relativi all\u2019itinerario seguito all\u2019interno dell\u2019Applicazione, con particolare riferimento alla sequenza delle pagine consultate, ai parametri relativi al sistema operativo e all\u2019ambiente informatico dell\u2019Utente.<\/p>\n\n\n\n<p><strong>Utente<\/strong><\/p>\n\n\n\n<p>L\u2019individuo che utilizza questa Applicazione che, salvo ove diversamente specificato, coincide con l\u2019Interessato.<\/p>\n\n\n\n<p><strong>Interessato<\/strong><\/p>\n\n\n\n<p>La persona fisica cui si riferiscono i Dati Personali.<\/p>\n\n\n\n<p><strong>Responsabile del Trattamento (o Responsabile)<\/strong><\/p>\n\n\n\n<p>La persona fisica, giuridica, la pubblica amministrazione e qualsiasi altro ente che tratta dati personali per conto del Titolare, secondo quanto esposto nella presente privacy policy.<\/p>\n\n\n\n<p><strong>Titolare del Trattamento (o Titolare)<\/strong><\/p>\n\n\n\n<p>La persona fisica o giuridica, l\u2019autorit\u00e0 pubblica, il servizio o altro organismo che, singolarmente o insieme ad altri, determina le finalit\u00e0 e i mezzi del trattamento di dati personali e gli strumenti adottati, ivi comprese le misure di sicurezza relative al funzionamento ed alla fruizione di questa Applicazione. Il Titolare del Trattamento, salvo quanto diversamente specificato, \u00e8 il titolare di questa Applicazione.<\/p>\n\n\n\n<p><strong>Questa Applicazione<\/strong><\/p>\n\n\n\n<p>Lo strumento hardware o software mediante il quale sono raccolti e trattati i Dati Personali degli Utenti.<\/p>\n\n\n\n<p><strong>Servizio<\/strong><\/p>\n\n\n\n<p>Il Servizio fornito da questa Applicazione cos\u00ec come definito nei relativi termini (se presenti) su questo sito\/applicazione.<\/p>\n\n\n\n<p><strong>Unione Europea (o UE)<\/strong><\/p>\n\n\n\n<p>Salvo ove diversamente specificato, ogni riferimento all\u2019Unione Europea contenuto in questo documento si intende esteso a tutti gli attuali stati membri dell\u2019Unione Europea e dello Spazio Economico Europeo.<\/p>\n\n\n\n<p><strong>Cookie<\/strong><\/p>\n\n\n\n<p>Piccola porzione di dati conservata all\u2019interno del dispositivo dell\u2019Utente.<\/p>\n\n\n\n<p><strong>Riferimenti legali<\/strong><\/p>\n\n\n\n<p>Avviso agli Utenti europei: la presente informativa privacy \u00e8 redatta in adempimento degli obblighi previsti dall\u2019Art. 10 della Direttiva n. 95\/46\/CE, nonch\u00e9 a quanto previsto dalla Direttiva 2002\/58\/CE, come aggiornata dalla Direttiva 2009\/136\/CE, in materia di Cookie.<\/p>\n\n\n\n<p>Questa informativa privacy riguarda esclusivamente questa Applicazione.<\/p>\n\n\n\n<p>Ultima modifica: 2 gennaio 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Cookie sono costituiti da porzioni di codice installate all\u2019interno del browser che assistono il Titolare nell\u2019erogazione del Servizio in base alle finalit\u00e0 descritte. Alcune delle finalit\u00e0 di installazione dei Cookie potrebbero, inoltre, necessitare del consenso dell\u2019Utente. Quando l\u2019installazione di Cookies avviene sulla base del consenso, tale consenso pu\u00f2 essere revocato liberamente in ogni momento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-311","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cicloamatour.it\/strada\/wp-json\/wp\/v2\/pages\/311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cicloamatour.it\/strada\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cicloamatour.it\/strada\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cicloamatour.it\/strada\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cicloamatour.it\/strada\/wp-json\/wp\/v2\/comments?post=311"}],"version-history":[{"count":1,"href":"https:\/\/cicloamatour.it\/strada\/wp-json\/wp\/v2\/pages\/311\/revisions"}],"predecessor-version":[{"id":312,"href":"https:\/\/cicloamatour.it\/strada\/wp-json\/wp\/v2\/pages\/311\/revisions\/312"}],"wp:attachment":[{"href":"https:\/\/cicloamatour.it\/strada\/wp-json\/wp\/v2\/media?parent=311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}